{"id":58864,"date":"2024-05-06T13:02:37","date_gmt":"2024-05-06T11:02:37","guid":{"rendered":"https:\/\/saprenovation.com\/alaudis\/"},"modified":"2025-10-28T18:47:38","modified_gmt":"2025-10-28T17:47:38","slug":"alaudis-stara","status":"publish","type":"page","link":"https:\/\/saprenovation.com\/fr\/alaudis-stara\/","title":{"rendered":"Alaudis"},"content":{"rendered":"\n<div class=\"wp-block-group is-layout-constrained wp-container-core-group-is-layout-fa9b7e41 wp-block-group-is-layout-constrained\" style=\"margin-top:var(--wp--preset--spacing--30);margin-bottom:var(--wp--preset--spacing--60)\">\n<h2 class=\"wp-block-heading\">Alaudis<\/h2>\n\n\n\n<p>SAP Alaudis est un piano extraordinaire con\u00e7u pour capturer la beaut\u00e9 et le son enchanteurs du chant de l&rsquo;alouette. M\u00e9ticuleusement fabriqu\u00e9 par une \u00e9quipe d&rsquo;artisans et d&rsquo;ing\u00e9nieurs qualifi\u00e9s, ce piano allie des ann\u00e9es d&rsquo;exp\u00e9rience, d&rsquo;innovation et la beaut\u00e9 de la nature.<\/p>\n\n\n\n<p>Le c\u0153ur d&rsquo;Alaudis r\u00e9side dans la table d&rsquo;harmonie con\u00e7ue par des experts et fabriqu\u00e9e en bois d&rsquo;\u00e9pic\u00e9a de la plus haute qualit\u00e9. Les propri\u00e9t\u00e9s naturelles de r\u00e9sonance et les qualit\u00e9s tonales contribuent \u00e0 la cr\u00e9ation d&rsquo;une table d&rsquo;harmonie capable de reproduire fid\u00e8lement des m\u00e9lodies \u00e9th\u00e9r\u00e9es comme le chant de l&rsquo;alouette susmentionn\u00e9e.<\/p>\n\n\n\n<p>Pour obtenir le son souhait\u00e9, les ing\u00e9nieurs de SAP ont mis en \u0153uvre des solutions modernes dans le domaine des cordes de piano. Ces cordes sont m\u00e9ticuleusement calibr\u00e9es et tendues pour cr\u00e9er un son riche, expressif et \u00e9vocateur qui se distingue par sa m\u00e9lodie des autres marques de pianos \u00e0 queue et de pianos droits.<\/p>\n\n\n\n<p>La m\u00e9canique et le clavier ont \u00e9t\u00e9 soigneusement con\u00e7us pour permettre une r\u00e9p\u00e9tition d\u00e9licate et un contr\u00f4le pr\u00e9cis afin que les pianistes puissent produire sans effort des nuances et des variations subtiles sans se sentir limit\u00e9s de quelque mani\u00e8re que ce soit.<br>L&rsquo;engagement de SAP Renovation dans le projet et l&rsquo;exp\u00e9rience garantit que chaque frappe est extr\u00eamement claire, permettant au pianiste d&rsquo;exprimer pleinement ses \u00e9motions musicales.<\/p>\n\n\n\n<p>Visuellement, SAP Alaudis Luxury s\u00e9duit par son \u00e9l\u00e9gance et son charme, tout en offrant un design v\u00e9ritablement intemporel.<\/p>\n\n\n<style>#jtg-61434 .modula-item .jtg-social a, .lightbox-socials.jtg-social a{ fill: #ffffff; color: #ffffff }#jtg-61434 .modula-item .jtg-social-expandable a, #jtg-61434 .modula-item .jtg-social-expandable-icons a{ fill: #ffffff; color: #ffffff }#jtg-61434 .modula-item .jtg-social svg, .lightbox-socials.jtg-social svg { height: 16px; width: 16px }#jtg-61434 .modula-item .jtg-social-expandable svg { height: 16px; width: 16px }#jtg-61434 .modula-item .jtg-social-expandable-icons svg { height: 16px; width: 16px }#jtg-61434 .modula-item .jtg-social a:not(:last-child), .lightbox-socials.jtg-social a:not(:last-child) { margin-right: 10px }#jtg-61434 .modula-item .jtg-social-expandable-icons { gap: 10px }#jtg-61434 .modula-item .no-socials{ display:none; }#jtg-61434 .modula-item .figc {color:#ffffff;}#jtg-61434 .modula-item .modula-item-content { transform: scale(1); }#jtg-61434 { width:100%;}#jtg-61434 .modula-items{height:800px;}@media screen and (max-width: 992px) {#jtg-61434 .modula-items{height:800px;}}@media screen and (max-width: 768px) {#jtg-61434 .modula-items{height:800px;}}#jtg-61434 .modula-items .figc p.description { font-size:14px; }#jtg-61434 .modula-items .figc p.description { color:#ffffff;}#jtg-61434.modula-gallery .modula-item > a, #jtg-61434.modula-gallery .modula-item, #jtg-61434.modula-gallery .modula-item-content > a:not(.modula-no-follow) { cursor:zoom-in; } #jtg-61434.modula-gallery .modula-item-content .modula-no-follow { cursor: default; } #jtg-61434 .modula-item .modula-item-overlay, #jtg-61434 .modula-item.effect-layla, #jtg-61434  .modula-item.effect-ruby,#jtg-61434 .modula-item.effect-bubba,#jtg-61434 .modula-item.effect-sarah,#jtg-61434 .modula-item.effect-milo,#jtg-61434 .modula-item.effect-julia,#jtg-61434 .modula-item.effect-hera,#jtg-61434 .modula-item.effect-winston,#jtg-61434 .modula-item.effect-selena,#jtg-61434 .modula-item.effect-terry,#jtg-61434 .modula-item.effect-phoebe,#jtg-61434 .modula-item.effect-apollo{ background-color:#ffffff; }#jtg-61434  .modula-item.effect-oscar { background: -webkit-linear-gradient(45deg,#ffffff 0,#9b4a1b 40%,#ffffff 100%);background: linear-gradient(45deg,#ffffff 0,#9b4a1b 40%,#ffffff 100%);}#jtg-61434  .modula-item.effect-roxy {background: -webkit-linear-gradient(45deg,#ffffff 0,#05abe0 100%);background: linear-gradient(45deg,#ffffff 0,#05abe0 100%);}#jtg-61434 .modula-item.effect-dexter {background: -webkit-linear-gradient(top,#ffffff 0,rgba(104,60,19,1) 100%); background: linear-gradient(to bottom,#ffffff 0,rgba(104,60,19,1) 100%);}#jtg-61434  .modula-item.effect-jazz {background: -webkit-linear-gradient(-45deg,#ffffff 0,#f33f58 100%);background: linear-gradient(-45deg,#ffffff 0,#f33f58 100%);}#jtg-61434 .modula-item.effect-lexi {background: -webkit-linear-gradient(-45deg,#ffffff 0,#fff 100%);background: linear-gradient(-45deg,#ffffff 0,#fff 100%);}#jtg-61434 .modula-item.effect-duke {background: -webkit-linear-gradient(-45deg,#ffffff 0,#cc6055 100%);background: linear-gradient(-45deg,#ffffff 0,#cc6055 100%);}#jtg-61434 .modula-item.effect-ming .figc::before {border: 2px solid #ffffff; box-shadow: 0 0 0 100vmax rgba(255,255,255,0.5);}#jtg-61434 .modula-item:hover img { opacity: 0.5; }#jtg-61434 .jtg-title {font-weight:400; }#jtg-61434 p.description {font-weight:normal; }#jtg-61434:not(.modula-loaded-scale)  .modula-item .modula-item-content { transform: scale(1) translate(0px,0px) rotate(0deg); }#jtg-61434:not(.modula-loaded-scale)  .modula-item.effect-under .modula-item-image-continer { transform: scale(1) translate(0px,0px) rotate(0deg); }@keyframes modulaScaling { 0% {transform: scale(1) translate(0px,p0x) rotate(0deg);} 50%{transform: scale(1) translate(0px,0px) rotate(0deg);}100%{transform: scale(1) translate(0px,p0x) rotate(0deg);}}#jtg-61434.modula-gallery .modula-item.effect-terry .jtg-social a:not(:last-child){margin-bottom:10px;}.modula-fancybox-container.modula-lightbox-jtg-61434 .modula-fancybox-caption .modula-fancybox-caption__body, .modula-fancybox-container.modula-lightbox-jtg-61434 .modula-fancybox-caption .modula-fancybox-caption__body p {text-align:left}html body .modula.modula-columns .modula-items.grid-gallery .modula-item.effect-under .modula-item-content { height:auto;}@media all and (max-width: 768px) { .modula-gallery .modula-item.effect-under.modula-caption-effect-item.jg-entry { margin-top: 10px; } }#jtg-61434 .modula-item.effect-under .modula-item-image-continer { transform: scale(1) }.modula-fancybox-container.modula-lightbox-jtg-61434 .fancybox__caption {align-self:flex-start}.modula-best-grid-gallery .modula-fancybox-container.modula-lightbox-jtg-61434 {--fancybox-bg:#ffffff;--fancybox-opacity:1 !important;}.modula-fancybox-container.modula-lightbox-jtg-61434 .fancybox__caption {align-self:flex-start}@media screen and (max-width:480px){#jtg-61434 .modula-item .figc .jtg-title {  font-size: 12px; }#jtg-61434 .modula-items .figc p.description { color:#ffffff;font-size:10px; }}<\/style>\n<div  id=\"jtg-61434\" class=\"modula modula-gallery modula-creative-gallery\" data-config=\"{&quot;height&quot;:800,&quot;tabletHeight&quot;:800,&quot;mobileHeight&quot;:800,&quot;desktopHeight&quot;:800,&quot;enableTwitter&quot;:false,&quot;enableWhatsapp&quot;:false,&quot;enableFacebook&quot;:false,&quot;enablePinterest&quot;:false,&quot;enableLinkedin&quot;:false,&quot;enableEmail&quot;:false,&quot;randomFactor&quot;:0.5,&quot;type&quot;:&quot;creative-gallery&quot;,&quot;columns&quot;:12,&quot;gutter&quot;:10,&quot;mobileGutter&quot;:10,&quot;tabletGutter&quot;:10,&quot;desktopGutter&quot;:10,&quot;enableResponsive&quot;:&quot;0&quot;,&quot;tabletColumns&quot;:2,&quot;mobileColumns&quot;:1,&quot;lazyLoad&quot;:0,&quot;lightboxOpts&quot;:{&quot;animated&quot;:true,&quot;Thumbs&quot;:{&quot;type&quot;:&quot;modern&quot;,&quot;showOnStart&quot;:false,&quot;position&quot;:&quot;bottom&quot;},&quot;Toolbar&quot;:{&quot;display&quot;:{&quot;right&quot;:[&quot;fullscreen&quot;,&quot;zoomIn&quot;,&quot;zoomOut&quot;,&quot;close&quot;],&quot;left&quot;:[&quot;infobar&quot;]},&quot;enabled&quot;:true},&quot;Carousel&quot;:{&quot;Panzoom&quot;:{&quot;touch&quot;:true},&quot;infinite&quot;:false,&quot;transition&quot;:&quot;fade&quot;},&quot;keyboard&quot;:{&quot;Escape&quot;:&quot;close&quot;,&quot;Delete&quot;:&quot;close&quot;,&quot;Backspace&quot;:&quot;close&quot;,&quot;PageUp&quot;:&quot;next&quot;,&quot;PageDown&quot;:&quot;prev&quot;,&quot;ArrowUp&quot;:&quot;prev&quot;,&quot;ArrowDown&quot;:&quot;next&quot;,&quot;ArrowRight&quot;:&quot;next&quot;,&quot;ArrowLeft&quot;:&quot;prev&quot;},&quot;touch&quot;:{&quot;vertical&quot;:true,&quot;momentum&quot;:true},&quot;backdropClick&quot;:false,&quot;l10n&quot;:{&quot;CLOSE&quot;:&quot;Close&quot;,&quot;NEXT&quot;:&quot;Next&quot;,&quot;PREV&quot;:&quot;Previous&quot;,&quot;Error&quot;:&quot;The requested content cannot be loaded. Please try again later.&quot;,&quot;PLAY_START&quot;:&quot;Start slideshow&quot;,&quot;PLAY_STOP&quot;:&quot;Pause slideshow&quot;,&quot;FULL_SCREEN&quot;:&quot;Full screen&quot;,&quot;THUMBS&quot;:&quot;Thumbnails&quot;,&quot;DOWNLOAD&quot;:&quot;Download&quot;,&quot;SHARE&quot;:&quot;Share&quot;,&quot;ZOOM&quot;:&quot;Zoom&quot;,&quot;EMAIL&quot;:&quot;Here is the link to the image : %%image_link%% and this is the link to the gallery : %%gallery_link%%&quot;,&quot;MODAL&quot;:&quot;You can close this modal content with the ESC key&quot;,&quot;ERROR&quot;:&quot;Something Went Wrong, Please Try Again Later&quot;,&quot;IMAGE_ERROR&quot;:&quot;Image Not Found&quot;,&quot;ELEMENT_NOT_FOUND&quot;:&quot;HTML Element Not Found&quot;,&quot;AJAX_NOT_FOUND&quot;:&quot;Error Loading AJAX : Not Found&quot;,&quot;AJAX_FORBIDDEN&quot;:&quot;Error Loading AJAX : Forbidden&quot;,&quot;IFRAME_ERROR&quot;:&quot;Error Loading Page&quot;,&quot;TOGGLE_ZOOM&quot;:&quot;Toggle zoom level&quot;,&quot;TOGGLE_THUMBS&quot;:&quot;Toggle thumbnails&quot;,&quot;TOGGLE_SLIDESHOW&quot;:&quot;Toggle slideshow&quot;,&quot;TOGGLE_FULLSCREEN&quot;:&quot;Toggle full-screen mode&quot;},&quot;Images&quot;:{&quot;Panzoom&quot;:{&quot;maxScale&quot;:2}},&quot;toolbar&quot;:true,&quot;wheel&quot;:false,&quot;animationEffect&quot;:&quot;false&quot;,&quot;transitionEffect&quot;:&quot;fade&quot;,&quot;Fullscreen&quot;:{&quot;autoStart&quot;:true},&quot;mainClass&quot;:&quot;modula-fancybox-container modula-lightbox-jtg-61434&quot;,&quot;Html&quot;:{&quot;videoAutoplay&quot;:0,&quot;videoTpl&quot;:&quot;&lt;video class=\\&quot;fancybox__html5video\\&quot; controls muted playsinline controlsList controlsList=\\&quot;nodownload\\&quot; poster=\\&quot;{{poster}}\\&quot; src=\\&quot;{{src}}\\&quot; type=\\&quot;{{format}}\\&quot; &gt;  Sorry, your browser doesn&#039;t support embedded videos, &lt;a href=\\&quot;{{src}}\\&quot;&gt; download &lt;\\\/a&gt; and watch with your favorite video player! &lt;\\\/video&gt;&quot;}},&quot;inView&quot;:false,&quot;email_subject&quot;:&quot;Check out this awesome image !!&quot;,&quot;email_message&quot;:&quot;Here is the link to the image : %%image_link%% and this is the link to the gallery : %%gallery_link%%&quot;,&quot;lightbox&quot;:&quot;fancybox&quot;,&quot;filterClick&quot;:&quot;0&quot;,&quot;dropdownFilters&quot;:&quot;0&quot;,&quot;defaultActiveFilter&quot;:&quot;all&quot;,&quot;initLightbox&quot;:&quot;modula_pro_init_lightbox&quot;,&quot;haveFilters&quot;:0,&quot;lightbox_devices&quot;:&quot;both&quot;}\">\n\n\t\n\t<div  class=\"modula-items\">\n\t\t<div class=\"modula-item effect-pufrobo jtg-filter-all jtg-filter-\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t\t\t\n\t\t\t\t\t<a role=\"button\" tabindex=\"0\" rel=\"jtg-61434\" data-caption=\"\" aria-label=\"Open image in lightbox\" data-thumb=\"https:\/\/wp-modula.b-cdn.net\/spai\/q_lossless,ret_img,w_150,h_150\/https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/f-_MG_0580-copy-150x150.jpg\" class=\"tile-inner modula-item-link\"><\/a>\n\t\t\n\t\t<img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-61428\"  data-valign=\"middle\" data-halign=\"center\" alt=\"Czterech m\u0119\u017cczyzn uk\u0142ada p\u0142yty drewniane przy d\u0142ugim stole w warsztacie z widocznym zegarem.\" data-full=\"https:\/\/wp-modula.b-cdn.net\/spai\/q_lossless,ret_img\/https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/f-_MG_0580-copy.jpg\" title=\"Praca czterech m\u0119\u017cczyzn nad drewnianymi p\u0142ytami w warsztacie\" width=\"1024\" height=\"682\" src=\"https:\/\/wp-modula.b-cdn.net\/spai\/q_lossless,ret_img,w_1024,h_682\/https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/f-_MG_0580-copy-1024x682.jpg\" data-src=\"https:\/\/wp-modula.b-cdn.net\/spai\/q_lossless,ret_img,w_1024,h_682\/https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/f-_MG_0580-copy-1024x682.jpg\" data-caption=\"Czterech m\u0119\u017cczyzn pracuje przy d\u0142ugim stole w warsztacie, uk\u0142adaj\u0105c du\u017ce p\u0142yty drewna lub materia\u0142u drewnopodobnego. W tle widoczne s\u0105 elementy drewniane, \u015bwiec\u0105ce lampy sufitowe oraz zegar na \u015bcianie.\" srcset=\"https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/f-_MG_0580-copy-1024x682.jpg 1024w, https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/f-_MG_0580-copy-600x400.jpg 600w, https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/f-_MG_0580-copy-300x200.jpg 300w, https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/f-_MG_0580-copy-768x512.jpg 768w, https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/f-_MG_0580-copy-1536x1024.jpg 1536w, https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/f-_MG_0580-copy.jpg 2000w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\n\t\t<div class=\"figc\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo jtg-filter-all jtg-filter-\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t\t\t\n\t\t\t\t\t<a role=\"button\" tabindex=\"0\" rel=\"jtg-61434\" data-caption=\"\" aria-label=\"Open image in lightbox\" data-thumb=\"https:\/\/wp-modula.b-cdn.net\/spai\/q_lossless,ret_img,w_150,h_150\/https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/f-_MG_0595-copy-150x150.jpg\" class=\"tile-inner modula-item-link\"><\/a>\n\t\t\n\t\t<img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-61416\"  data-valign=\"middle\" data-halign=\"center\" alt=\"Czterech m\u0119\u017cczyzn w warsztacie nak\u0142ada i rozprowadza materia\u0142 na drewnianych panelach przy stole.\" data-full=\"https:\/\/wp-modula.b-cdn.net\/spai\/q_lossless,ret_img\/https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/f-_MG_0595-copy.jpg\" title=\"M\u0119\u017cczy\u017ani nak\u0142adaj\u0105 materia\u0142 na powierzchnie w warsztacie SAP\" data-caption=\"Czterech m\u0119\u017cczyzn pracuje przy d\u0142ugim stole w warsztacie, nak\u0142adaj\u0105c i rozprowadzaj\u0105c materia\u0142 na p\u0142askich, prostok\u0105tnych powierzchniach. Wszyscy maj\u0105 na sobie ciemne ubrania z logo SAP i r\u0119kawice ochronne. W tle wida\u0107 narz\u0119dzia i inne oprzyrz\u0105dowanie warsztatowe.\" src=\"https:\/\/wp-modula.b-cdn.net\/spai\/q_lossless,ret_img,w_1024,h_682\/https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/f-_MG_0595-copy-1024x682.jpg\" data-src=\"https:\/\/wp-modula.b-cdn.net\/spai\/q_lossless,ret_img,w_1024,h_682\/https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/f-_MG_0595-copy-1024x682.jpg\" width=\"1024\" height=\"682\" srcset=\"https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/f-_MG_0595-copy-1024x682.jpg 1024w, https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/f-_MG_0595-copy-600x400.jpg 600w, https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/f-_MG_0595-copy-300x200.jpg 300w, https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/f-_MG_0595-copy-768x512.jpg 768w, https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/f-_MG_0595-copy-1536x1024.jpg 1536w, https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/f-_MG_0595-copy.jpg 2000w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\n\t\t<div class=\"figc\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo jtg-filter-all jtg-filter-\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t\t\t\n\t\t\t\t\t<a role=\"button\" tabindex=\"0\" rel=\"jtg-61434\" data-caption=\"\" aria-label=\"Open image in lightbox\" data-thumb=\"https:\/\/wp-modula.b-cdn.net\/spai\/q_lossless,ret_img,w_150,h_150\/https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/f-_MG_0617-copy-150x150.jpg\" class=\"tile-inner modula-item-link\"><\/a>\n\t\t\n\t\t<img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-61410\"  data-valign=\"middle\" data-halign=\"center\" alt=\"Czterech m\u0119\u017cczyzn rozprowadza materia\u0142 na d\u0142ugich powierzchniach w warsztacie.\" data-full=\"https:\/\/wp-modula.b-cdn.net\/spai\/q_lossless,ret_img\/https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/f-_MG_0617-copy.jpg\" title=\"M\u0119\u017cczy\u017ani rozprowadzaj\u0105 materia\u0142 w warsztacie\" data-caption=\"Czterech m\u0119\u017cczyzn pracuje w warsztacie, rozprowadzaj\u0105c materia\u0142 na d\u0142ugich, prostych powierzchniach. W tle znajduj\u0105 si\u0119 r\u00f3\u017cne narz\u0119dzia i elementy wyposa\u017cenia warsztatu.\" src=\"https:\/\/wp-modula.b-cdn.net\/spai\/q_lossless,ret_img,w_1024,h_682\/https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/f-_MG_0617-copy-1024x682.jpg\" data-src=\"https:\/\/wp-modula.b-cdn.net\/spai\/q_lossless,ret_img,w_1024,h_682\/https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/f-_MG_0617-copy-1024x682.jpg\" width=\"1024\" height=\"682\" srcset=\"https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/f-_MG_0617-copy-1024x682.jpg 1024w, https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/f-_MG_0617-copy-600x400.jpg 600w, https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/f-_MG_0617-copy-300x200.jpg 300w, https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/f-_MG_0617-copy-768x512.jpg 768w, https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/f-_MG_0617-copy-1536x1024.jpg 1536w, https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/f-_MG_0617-copy.jpg 2000w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\n\t\t<div class=\"figc\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo jtg-filter-all jtg-filter-\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t\t\t\n\t\t\t\t\t<a role=\"button\" tabindex=\"0\" rel=\"jtg-61434\" data-caption=\"\" aria-label=\"Open image in lightbox\" data-thumb=\"https:\/\/wp-modula.b-cdn.net\/spai\/q_lossless,ret_img,w_150,h_150\/https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/f-_MG_0695-copy-150x150.jpg\" class=\"tile-inner modula-item-link\"><\/a>\n\t\t\n\t\t<img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-61404\"  data-valign=\"middle\" data-halign=\"center\" alt=\"Zakrzywiona drewniana p\u0142yta zabezpieczona niebiesk\u0105 ta\u015bm\u0105 i metalowymi zaciskami w warsztacie.\" data-full=\"https:\/\/wp-modula.b-cdn.net\/spai\/q_lossless,ret_img\/https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/f-_MG_0695-copy.jpg\" title=\"Zakrzywiana drewniana p\u0142yta w metalowych zaciskach\" data-caption=\"Cz\u0119\u015bciowo zakrzywiona drewniana p\u0142yta przytrzymywana jest przez metalowe zaciski w warsztacie stolarskim. Na kraw\u0119dzi p\u0142yty znajduje si\u0119 niebieska ta\u015bma.\" src=\"https:\/\/wp-modula.b-cdn.net\/spai\/q_lossless,ret_img,w_1024,h_682\/https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/f-_MG_0695-copy-1024x682.jpg\" data-src=\"https:\/\/wp-modula.b-cdn.net\/spai\/q_lossless,ret_img,w_1024,h_682\/https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/f-_MG_0695-copy-1024x682.jpg\" width=\"1024\" height=\"682\" srcset=\"https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/f-_MG_0695-copy-1024x682.jpg 1024w, https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/f-_MG_0695-copy-600x400.jpg 600w, https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/f-_MG_0695-copy-300x200.jpg 300w, https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/f-_MG_0695-copy-768x512.jpg 768w, https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/f-_MG_0695-copy-1536x1024.jpg 1536w, https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/f-_MG_0695-copy.jpg 2000w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\n\t\t<div class=\"figc\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo jtg-filter-all jtg-filter-\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t\t\t\n\t\t\t\t\t<a role=\"button\" tabindex=\"0\" rel=\"jtg-61434\" data-caption=\"\" aria-label=\"Open image in lightbox\" data-thumb=\"https:\/\/wp-modula.b-cdn.net\/spai\/q_lossless,ret_img,w_150,h_150\/https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/f-_MG_1309-copy-150x150.jpg\" class=\"tile-inner modula-item-link\"><\/a>\n\t\t\n\t\t<img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-61398\"  data-valign=\"middle\" data-halign=\"center\" alt=\"Dw\u00f3ch m\u0119\u017cczyzn ocenia dotykiem zakrzywion\u0105 drewnian\u0105 konstrukcj\u0119 w jasnym warsztacie.\" data-full=\"https:\/\/wp-modula.b-cdn.net\/spai\/q_lossless,ret_img\/https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/f-_MG_1309-copy.jpg\" title=\"M\u0119\u017cczy\u017ani badaj\u0105 drewnian\u0105 zakrzywion\u0105 powierzchni\u0119.\" data-caption=\"Dw\u00f3ch m\u0119\u017cczyzn sprawdza i dotyka du\u017c\u0105, zakrzywion\u0105 powierzchni\u0119 wykonan\u0105 z drewna w jasnym pomieszczeniu.\" src=\"https:\/\/wp-modula.b-cdn.net\/spai\/q_lossless,ret_img,w_1024,h_682\/https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/f-_MG_1309-copy-1024x682.jpg\" data-src=\"https:\/\/wp-modula.b-cdn.net\/spai\/q_lossless,ret_img,w_1024,h_682\/https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/f-_MG_1309-copy-1024x682.jpg\" width=\"1024\" height=\"682\" srcset=\"https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/f-_MG_1309-copy-1024x682.jpg 1024w, https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/f-_MG_1309-copy-600x400.jpg 600w, https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/f-_MG_1309-copy-300x200.jpg 300w, https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/f-_MG_1309-copy-768x512.jpg 768w, https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/f-_MG_1309-copy-1536x1024.jpg 1536w, https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/f-_MG_1309-copy.jpg 2000w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\n\t\t<div class=\"figc\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo jtg-filter-all jtg-filter-\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t\t\t\n\t\t\t\t\t<a role=\"button\" tabindex=\"0\" rel=\"jtg-61434\" data-caption=\"\" aria-label=\"Open image in lightbox\" data-thumb=\"https:\/\/wp-modula.b-cdn.net\/spai\/q_lossless,ret_img,w_150,h_150\/https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/f-_MG_1338-copy-150x150.jpg\" class=\"tile-inner modula-item-link\"><\/a>\n\t\t\n\t\t<img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-61392\"  data-valign=\"middle\" data-halign=\"center\" alt=\"M\u0119\u017cczyzna szlifuje drewniany element w warsztacie stolarskim z narz\u0119dziami w tle.\" data-full=\"https:\/\/wp-modula.b-cdn.net\/spai\/q_lossless,ret_img\/https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/f-_MG_1338-copy.jpg\" title=\"M\u0119\u017cczyzna szlifuj\u0105cy drewniany element w warsztacie\" data-caption=\"M\u0119\u017cczyzna z brod\u0105 i siwymi w\u0142osami szlifuje drewniany element w warsztacie stolarskim. W tle znajduj\u0105 si\u0119 narz\u0119dzia i drewniane formy.\" src=\"https:\/\/wp-modula.b-cdn.net\/spai\/q_lossless,ret_img,w_1024,h_682\/https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/f-_MG_1338-copy-1024x682.jpg\" data-src=\"https:\/\/wp-modula.b-cdn.net\/spai\/q_lossless,ret_img,w_1024,h_682\/https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/f-_MG_1338-copy-1024x682.jpg\" width=\"1024\" height=\"682\" srcset=\"https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/f-_MG_1338-copy-1024x682.jpg 1024w, https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/f-_MG_1338-copy-600x400.jpg 600w, https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/f-_MG_1338-copy-300x200.jpg 300w, https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/f-_MG_1338-copy-768x512.jpg 768w, https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/f-_MG_1338-copy-1536x1024.jpg 1536w, https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/f-_MG_1338-copy.jpg 2000w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\n\t\t<div class=\"figc\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo jtg-filter-all jtg-filter-\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t\t\t\n\t\t\t\t\t<a role=\"button\" tabindex=\"0\" rel=\"jtg-61434\" data-caption=\"\" aria-label=\"Open image in lightbox\" data-thumb=\"https:\/\/wp-modula.b-cdn.net\/spai\/q_lossless,ret_img,w_150,h_150\/https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/f-_MG_1339-copy-150x150.jpg\" class=\"tile-inner modula-item-link\"><\/a>\n\t\t\n\t\t<img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-61386\"  data-valign=\"middle\" data-halign=\"center\" alt=\"M\u0119\u017cczyzna w\u0105chaj\u0105cy kawa\u0142ek drewna w warsztacie stolarskim z narz\u0119dziami w tle\" data-full=\"https:\/\/wp-modula.b-cdn.net\/spai\/q_lossless,ret_img\/https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/f-_MG_1339-copy.jpg\" title=\"M\u0119\u017cczyzna w\u0105chaj\u0105cy drewno w warsztacie stolarskim\" data-caption=\"M\u0119\u017cczyzna dok\u0142adnie w\u0105cha kawa\u0142ek drewna w warsztacie stolarskim, gdzie w tle widoczne s\u0105 drewniane elementy i narz\u0119dzia.\" src=\"https:\/\/wp-modula.b-cdn.net\/spai\/q_lossless,ret_img,w_1024,h_682\/https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/f-_MG_1339-copy-1024x682.jpg\" data-src=\"https:\/\/wp-modula.b-cdn.net\/spai\/q_lossless,ret_img,w_1024,h_682\/https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/f-_MG_1339-copy-1024x682.jpg\" width=\"1024\" height=\"682\" srcset=\"https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/f-_MG_1339-copy-1024x682.jpg 1024w, https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/f-_MG_1339-copy-600x400.jpg 600w, https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/f-_MG_1339-copy-300x200.jpg 300w, https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/f-_MG_1339-copy-768x512.jpg 768w, https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/f-_MG_1339-copy-1536x1024.jpg 1536w, https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/f-_MG_1339-copy.jpg 2000w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\n\t\t<div class=\"figc\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo jtg-filter-all jtg-filter-\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t\t\t\n\t\t\t\t\t<a role=\"button\" tabindex=\"0\" rel=\"jtg-61434\" data-caption=\"\" aria-label=\"Open image in lightbox\" data-thumb=\"https:\/\/wp-modula.b-cdn.net\/spai\/q_lossless,ret_img,w_150,h_150\/https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/f-_MG_1361-copy-150x150.jpg\" class=\"tile-inner modula-item-link\"><\/a>\n\t\t\n\t\t<img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-61380\"  data-valign=\"middle\" data-halign=\"center\" alt=\"Stos surowych drewnianych desek i r\u0119ka unosz\u0105ca jedn\u0105 z desek w warsztacie.\" data-full=\"https:\/\/wp-modula.b-cdn.net\/spai\/q_lossless,ret_img\/https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/f-_MG_1361-copy.jpg\" title=\"Surowe drewniane deski z r\u0119k\u0105 unosz\u0105c\u0105 jedn\u0105 desk\u0119\" data-caption=\"Stos surowych drewnianych desek, zbli\u017cenie na r\u0119k\u0119 unosz\u0105c\u0105 jedn\u0105 z desek.\" src=\"https:\/\/wp-modula.b-cdn.net\/spai\/q_lossless,ret_img,w_1024,h_682\/https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/f-_MG_1361-copy-1024x682.jpg\" data-src=\"https:\/\/wp-modula.b-cdn.net\/spai\/q_lossless,ret_img,w_1024,h_682\/https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/f-_MG_1361-copy-1024x682.jpg\" width=\"1024\" height=\"682\" srcset=\"https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/f-_MG_1361-copy-1024x682.jpg 1024w, https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/f-_MG_1361-copy-600x400.jpg 600w, https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/f-_MG_1361-copy-300x200.jpg 300w, https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/f-_MG_1361-copy-768x512.jpg 768w, https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/f-_MG_1361-copy-1536x1024.jpg 1536w, https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/f-_MG_1361-copy.jpg 2000w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\n\t\t<div class=\"figc\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo jtg-filter-all jtg-filter-\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t\t\t\n\t\t\t\t\t<a role=\"button\" tabindex=\"0\" rel=\"jtg-61434\" data-caption=\"\" aria-label=\"Open image in lightbox\" data-thumb=\"https:\/\/wp-modula.b-cdn.net\/spai\/q_lossless,ret_img,w_150,h_150\/https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/f-_MG_1364-copy-150x150.jpg\" class=\"tile-inner modula-item-link\"><\/a>\n\t\t\n\t\t<img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-61374\"  data-valign=\"middle\" data-halign=\"center\" alt=\"D\u0142o\u0144 wskazuje na stos surowych p\u0142yt drewnianych o r\u00f3\u017cnych grubo\u015bciach w warsztacie.\" data-full=\"https:\/\/wp-modula.b-cdn.net\/spai\/q_lossless,ret_img\/https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/f-_MG_1364-copy.jpg\" title=\"M\u0119ska d\u0142o\u0144 wskazuj\u0105ca na stos surowych p\u0142yt drewnianych w warsztacie\" data-caption=\"D\u0142o\u0144 m\u0119\u017cczyzny wskazuje na stos nieobrobionych p\u0142yt drewnianych o r\u00f3\u017cnych grubo\u015bciach u\u0142o\u017conych w warsztacie.\" src=\"https:\/\/wp-modula.b-cdn.net\/spai\/q_lossless,ret_img,w_1024,h_682\/https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/f-_MG_1364-copy-1024x682.jpg\" data-src=\"https:\/\/wp-modula.b-cdn.net\/spai\/q_lossless,ret_img,w_1024,h_682\/https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/f-_MG_1364-copy-1024x682.jpg\" width=\"1024\" height=\"682\" srcset=\"https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/f-_MG_1364-copy-1024x682.jpg 1024w, https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/f-_MG_1364-copy-600x400.jpg 600w, https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/f-_MG_1364-copy-300x200.jpg 300w, https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/f-_MG_1364-copy-768x512.jpg 768w, https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/f-_MG_1364-copy-1536x1024.jpg 1536w, https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/f-_MG_1364-copy.jpg 2000w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\n\t\t<div class=\"figc\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo jtg-filter-all jtg-filter-\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t\t\t\n\t\t\t\t\t<a role=\"button\" tabindex=\"0\" rel=\"jtg-61434\" data-caption=\"\" aria-label=\"Open image in lightbox\" data-thumb=\"https:\/\/wp-modula.b-cdn.net\/spai\/q_lossless,ret_img,w_150,h_150\/https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/f-_MG_1390-copy-150x150.jpg\" class=\"tile-inner modula-item-link\"><\/a>\n\t\t\n\t\t<img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-61368\"  data-valign=\"middle\" data-halign=\"center\" alt=\"D\u0142o\u0144 wskazuj\u0105ca na drewnian\u0105 desk\u0119 trzyman\u0105 przez drug\u0105 osob\u0119.\" data-full=\"https:\/\/wp-modula.b-cdn.net\/spai\/q_lossless,ret_img\/https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/f-_MG_1390-copy.jpg\" title=\"Wskazuj\u0105ca d\u0142o\u0144 na drewnian\u0105 desk\u0119\" data-caption=\"D\u0142o\u0144 wskazuj\u0105ca na powierzchni\u0119 drewnianej deski trzymanej przez drug\u0105 osob\u0119.\" src=\"https:\/\/wp-modula.b-cdn.net\/spai\/q_lossless,ret_img,w_1024,h_682\/https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/f-_MG_1390-copy-1024x682.jpg\" data-src=\"https:\/\/wp-modula.b-cdn.net\/spai\/q_lossless,ret_img,w_1024,h_682\/https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/f-_MG_1390-copy-1024x682.jpg\" width=\"1024\" height=\"682\" srcset=\"https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/f-_MG_1390-copy-1024x682.jpg 1024w, https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/f-_MG_1390-copy-600x400.jpg 600w, https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/f-_MG_1390-copy-300x200.jpg 300w, https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/f-_MG_1390-copy-768x512.jpg 768w, https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/f-_MG_1390-copy-1536x1024.jpg 1536w, https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/f-_MG_1390-copy.jpg 2000w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\n\t\t<div class=\"figc\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo jtg-filter-all jtg-filter-\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t\t\t\n\t\t\t\t\t<a role=\"button\" tabindex=\"0\" rel=\"jtg-61434\" data-caption=\"\" aria-label=\"Open image in lightbox\" data-thumb=\"https:\/\/wp-modula.b-cdn.net\/spai\/q_lossless,ret_img,w_150,h_150\/https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/fc-_MG_0551-copy-150x150.jpg\" class=\"tile-inner modula-item-link\"><\/a>\n\t\t\n\t\t<img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-61422\"  data-valign=\"middle\" data-halign=\"center\" alt=\"Dwaj m\u0119\u017cczy\u017ani wyginaj\u0105 i zaciskaj\u0105 arkusze sklejki w warsztacie stolarskim.\" data-full=\"https:\/\/wp-modula.b-cdn.net\/spai\/q_lossless,ret_img\/https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/fc-_MG_0551-copy.jpg\" title=\"Praca w warsztacie stolarskim z gi\u0119ciem sklejki\" data-caption=\"Dwaj m\u0119\u017cczy\u017ani pracuj\u0105 w warsztacie stolarskim, wyginaj\u0105c i zaciskaj\u0105c du\u017ce, elastyczne arkusze sklejki na stole roboczym. Wok\u00f3\u0142 nich znajduj\u0105 si\u0119 narz\u0119dzia i materia\u0142y stolarskie.\" src=\"https:\/\/wp-modula.b-cdn.net\/spai\/q_lossless,ret_img,w_1024,h_682\/https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/fc-_MG_0551-copy-1024x682.jpg\" data-src=\"https:\/\/wp-modula.b-cdn.net\/spai\/q_lossless,ret_img,w_1024,h_682\/https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/fc-_MG_0551-copy-1024x682.jpg\" width=\"1024\" height=\"682\" srcset=\"https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/fc-_MG_0551-copy-1024x682.jpg 1024w, https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/fc-_MG_0551-copy-600x400.jpg 600w, https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/fc-_MG_0551-copy-300x200.jpg 300w, https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/fc-_MG_0551-copy-768x512.jpg 768w, https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/fc-_MG_0551-copy-1536x1024.jpg 1536w, https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/02\/fc-_MG_0551-copy.jpg 2000w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\n\t\t<div class=\"figc\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo jtg-filter-all jtg-filter-\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t\t\t\n\t\t\t\t\t<a role=\"button\" tabindex=\"0\" rel=\"jtg-61434\" data-caption=\"\" aria-label=\"Open image in lightbox\" data-thumb=\"https:\/\/wp-modula.b-cdn.net\/spai\/q_lossless,ret_img,w_150,h_150\/https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/10\/f-_MG_0568-copy-150x150.jpg\" class=\"tile-inner modula-item-link\"><\/a>\n\t\t\n\t\t<img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-69787\"  data-valign=\"middle\" data-halign=\"center\" alt=\"Podnoszona metalowa rama fortepianu nad sto\u0142em z drewnian\u0105 obudow\u0105 i narz\u0119dziami stolarskimi.\" data-full=\"https:\/\/wp-modula.b-cdn.net\/spai\/q_lossless,ret_img\/https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/10\/f-_MG_0568-copy.jpg\" title=\"Mechanizm fortepianu podnoszony za pomoc\u0105 pas\u00f3w nad sto\u0142em z narz\u0119dziami i ram\u0105 drewnian\u0105\" data-caption=\"Cz\u0119\u015b\u0107 mechanizmu fortepianu jest podnoszona za pomoc\u0105 pas\u00f3w, podczas gdy na stole roboczym le\u017c\u0105 narz\u0119dzia stolarskie i drewniana rama instrumentu.\" src=\"https:\/\/wp-modula.b-cdn.net\/spai\/q_lossless,ret_img,w_1024,h_683\/https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/10\/f-_MG_0568-copy-scaled-1024x683.jpg\" data-src=\"https:\/\/wp-modula.b-cdn.net\/spai\/q_lossless,ret_img,w_1024,h_683\/https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/10\/f-_MG_0568-copy-scaled-1024x683.jpg\" width=\"1024\" height=\"683\"\/>\n\t\t<div class=\"figc\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo jtg-filter-all jtg-filter-\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t\t\t\n\t\t\t\t\t<a role=\"button\" tabindex=\"0\" rel=\"jtg-61434\" data-caption=\"\" aria-label=\"Open image in lightbox\" data-thumb=\"https:\/\/wp-modula.b-cdn.net\/spai\/q_lossless,ret_img,w_150,h_150\/https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/10\/f-_MG_0570-copy-150x150.jpg\" class=\"tile-inner modula-item-link\"><\/a>\n\t\t\n\t\t<img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-69793\"  data-valign=\"middle\" data-halign=\"center\" alt=\"Elementy drewnianego modelu fortepianu na stole warsztatu stolarskiego z metalow\u0105 ram\u0105 unoszon\u0105 przez osob\u0119.\" data-full=\"https:\/\/wp-modula.b-cdn.net\/spai\/q_lossless,ret_img\/https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/10\/f-_MG_0570-copy.jpg\" title=\"Warsztat stolarski z modelem fortepianu i metalow\u0105 ram\u0105\" data-caption=\"Warsztat stolarski z elementami drewnianego modelu fortepianu na stole roboczym oraz metalow\u0105 ram\u0105 unoszon\u0105 przez osob\u0119.\" src=\"https:\/\/wp-modula.b-cdn.net\/spai\/q_lossless,ret_img,w_1024,h_683\/https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/10\/f-_MG_0570-copy-scaled-1024x683.jpg\" data-src=\"https:\/\/wp-modula.b-cdn.net\/spai\/q_lossless,ret_img,w_1024,h_683\/https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/10\/f-_MG_0570-copy-scaled-1024x683.jpg\" width=\"1024\" height=\"683\"\/>\n\t\t<div class=\"figc\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo jtg-filter-all jtg-filter-\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t\t\t\n\t\t\t\t\t<a role=\"button\" tabindex=\"0\" rel=\"jtg-61434\" data-caption=\"\" aria-label=\"Open image in lightbox\" data-thumb=\"https:\/\/wp-modula.b-cdn.net\/spai\/q_lossless,ret_img,w_150,h_150\/https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/10\/f-_MG_1326-copy-150x150.jpg\" class=\"tile-inner modula-item-link\"><\/a>\n\t\t\n\t\t<img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-69871\"  data-valign=\"middle\" data-halign=\"center\" alt=\"M\u0119\u017cczyzna w s\u0142uchawkach ochronnych obrabia drewniany element na koz\u0142ach w warsztacie.\" data-full=\"https:\/\/wp-modula.b-cdn.net\/spai\/q_lossless,ret_img\/https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/10\/f-_MG_1326-copy.jpg\" title=\"M\u0119\u017cczyzna pracuj\u0105cy przy drewnianym elemencie w warsztacie stolarskim\" data-caption=\"M\u0119\u017cczyzna w s\u0142uchawkach ochronnych pracuje nad drewnianym elementem, kt\u00f3ry jest umieszczony na dw\u00f3ch koz\u0142ach w warsztacie stolarskim. W tle wida\u0107 r\u00f3\u017cne materia\u0142y i narz\u0119dzia.\" src=\"https:\/\/wp-modula.b-cdn.net\/spai\/q_lossless,ret_img,w_1024,h_683\/https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/10\/f-_MG_1326-copy-scaled-1024x683.jpg\" data-src=\"https:\/\/wp-modula.b-cdn.net\/spai\/q_lossless,ret_img,w_1024,h_683\/https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/10\/f-_MG_1326-copy-scaled-1024x683.jpg\" width=\"1024\" height=\"683\"\/>\n\t\t<div class=\"figc\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo jtg-filter-all jtg-filter-\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t\t\t\n\t\t\t\t\t<a role=\"button\" tabindex=\"0\" rel=\"jtg-61434\" data-caption=\"\" aria-label=\"Open image in lightbox\" data-thumb=\"https:\/\/wp-modula.b-cdn.net\/spai\/q_lossless,ret_img,w_150,h_150\/https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/10\/f-_MG_1099-copy-150x150.jpg\" class=\"tile-inner modula-item-link\"><\/a>\n\t\t\n\t\t<img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-69805\"  data-valign=\"middle\" data-halign=\"center\" alt=\"M\u0119\u017cczyzna d\u0142utuje drewniany element na stole warsztatowym z narz\u0119dziami w tle.\" data-full=\"https:\/\/wp-modula.b-cdn.net\/spai\/q_lossless,ret_img\/https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/10\/f-_MG_1099-copy.jpg\" title=\"M\u0119\u017cczyzna rze\u017abi drewniany element w warsztacie stolarskim\" data-caption=\"M\u0119\u017cczyzna pracuje nad drewnianym elementem, korzystaj\u0105c z d\u0142uta w warsztacie stolarskim. Element spoczywa na dw\u00f3ch koz\u0142ach, a na jego powierzchni le\u017c\u0105 narz\u0119dzia, w tym m\u0142otek i d\u0142uta. W tle widoczne s\u0105 r\u00f3\u017cne narz\u0119dzia i materia\u0142y warsztatowe.\" src=\"https:\/\/wp-modula.b-cdn.net\/spai\/q_lossless,ret_img,w_1024,h_683\/https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/10\/f-_MG_1099-copy-scaled-1024x683.jpg\" data-src=\"https:\/\/wp-modula.b-cdn.net\/spai\/q_lossless,ret_img,w_1024,h_683\/https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/10\/f-_MG_1099-copy-scaled-1024x683.jpg\" width=\"1024\" height=\"683\"\/>\n\t\t<div class=\"figc\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo jtg-filter-all jtg-filter-\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t\t\t\n\t\t\t\t\t<a role=\"button\" tabindex=\"0\" rel=\"jtg-61434\" data-caption=\"\" aria-label=\"Open image in lightbox\" data-thumb=\"https:\/\/wp-modula.b-cdn.net\/spai\/q_lossless,ret_img,w_150,h_150\/https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/10\/f-_MG_1106-copy-150x150.jpg\" class=\"tile-inner modula-item-link\"><\/a>\n\t\t\n\t\t<img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-69811\"  data-valign=\"middle\" data-halign=\"center\" alt=\"M\u0119\u017cczyzna rze\u017abi drewniany element o zakrzywionym kszta\u0142cie na stole warsztatowym.\" data-full=\"https:\/\/wp-modula.b-cdn.net\/spai\/q_lossless,ret_img\/https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/10\/f-_MG_1106-copy.jpg\" title=\"M\u0119\u017cczyzna precyzyjnie rze\u017abi zakrzywiony drewniany element przy stole warsztatowym\" data-caption=\"M\u0119\u017cczyzna w okularach i r\u0119kawicach z narz\u0119dziem do rze\u017abienia precyzyjnie obrabia drewniany element o zakrzywionym kszta\u0142cie na stole warsztatowym, gdzie le\u017c\u0105 r\u00f3wnie\u017c inne narz\u0119dzia i wi\u00f3ry drewniane.\" src=\"https:\/\/wp-modula.b-cdn.net\/spai\/q_lossless,ret_img,w_1024,h_683\/https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/10\/f-_MG_1106-copy-scaled-1024x683.jpg\" data-src=\"https:\/\/wp-modula.b-cdn.net\/spai\/q_lossless,ret_img,w_1024,h_683\/https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/10\/f-_MG_1106-copy-scaled-1024x683.jpg\" width=\"1024\" height=\"683\"\/>\n\t\t<div class=\"figc\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo jtg-filter-all jtg-filter-\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t\t\t\n\t\t\t\t\t<a role=\"button\" tabindex=\"0\" rel=\"jtg-61434\" data-caption=\"\" aria-label=\"Open image in lightbox\" data-thumb=\"https:\/\/wp-modula.b-cdn.net\/spai\/q_lossless,ret_img,w_150,h_150\/https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/10\/f-_MG_1097-copy-150x150.jpg\" class=\"tile-inner modula-item-link\"><\/a>\n\t\t\n\t\t<img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-69799\"  data-valign=\"middle\" data-halign=\"center\" alt=\"R\u0119czne rze\u017abienie drewna na kraw\u0119dzi z u\u017cyciem narz\u0119dzia do skrobania i wi\u00f3rami.\" data-full=\"https:\/\/wp-modula.b-cdn.net\/spai\/q_lossless,ret_img\/https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/10\/f-_MG_1097-copy.jpg\" title=\"R\u0119czne rze\u017abienie drewna narz\u0119dziem do skrobania\" data-caption=\"Osoba rze\u017abi\u0105ca drewno r\u0119cznie, trzymaj\u0105c narz\u0119dzie do skrobania i pracuj\u0105ca nad kszta\u0142tem drewnianej powierzchni z wi\u00f3rami na niej.\" src=\"https:\/\/wp-modula.b-cdn.net\/spai\/q_lossless,ret_img,w_1024,h_683\/https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/10\/f-_MG_1097-copy-scaled-1024x683.jpg\" data-src=\"https:\/\/wp-modula.b-cdn.net\/spai\/q_lossless,ret_img,w_1024,h_683\/https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/10\/f-_MG_1097-copy-scaled-1024x683.jpg\" width=\"1024\" height=\"683\"\/>\n\t\t<div class=\"figc\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo jtg-filter-all jtg-filter-\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t\t\t\n\t\t\t\t\t<a role=\"button\" tabindex=\"0\" rel=\"jtg-61434\" data-caption=\"\" aria-label=\"Open image in lightbox\" data-thumb=\"https:\/\/wp-modula.b-cdn.net\/spai\/q_lossless,ret_img,w_150,h_150\/https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/10\/f-_MG_1162-copy-150x150.jpg\" class=\"tile-inner modula-item-link\"><\/a>\n\t\t\n\t\t<img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-69817\"  data-valign=\"middle\" data-halign=\"center\" alt=\"R\u0119ce w bia\u0142ych r\u0119kawicach strugaj\u0105 kraw\u0119d\u017a drewna przy pomocy narz\u0119dzia stolarskiego.\" data-full=\"https:\/\/wp-modula.b-cdn.net\/spai\/q_lossless,ret_img\/https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/10\/f-_MG_1162-copy.jpg\" title=\"Struganie drewnianej kraw\u0119dzi w r\u0119kawicach ochronnych\" data-caption=\"Osoba r\u0119cznie struga kraw\u0119d\u017a drewnianej powierzchni przy u\u017cyciu narz\u0119dzia do obr\u00f3bki drewna, nosz\u0105c bia\u0142e r\u0119kawice ochronne.\" src=\"https:\/\/wp-modula.b-cdn.net\/spai\/q_lossless,ret_img,w_1024,h_683\/https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/10\/f-_MG_1162-copy-scaled-1024x683.jpg\" data-src=\"https:\/\/wp-modula.b-cdn.net\/spai\/q_lossless,ret_img,w_1024,h_683\/https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/10\/f-_MG_1162-copy-scaled-1024x683.jpg\" width=\"1024\" height=\"683\"\/>\n\t\t<div class=\"figc\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo jtg-filter-all jtg-filter-\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t\t\t\n\t\t\t\t\t<a role=\"button\" tabindex=\"0\" rel=\"jtg-61434\" data-caption=\"\" aria-label=\"Open image in lightbox\" data-thumb=\"https:\/\/wp-modula.b-cdn.net\/spai\/q_lossless,ret_img,w_150,h_150\/https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/10\/f-_MG_1202-copy-150x150.jpg\" class=\"tile-inner modula-item-link\"><\/a>\n\t\t\n\t\t<img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-69823\"  data-valign=\"middle\" data-halign=\"center\" alt=\"R\u0119kawice d\u0142oni d\u0142utuj\u0105 drewniany element z wi\u00f3rami na stole do pracy.\" data-full=\"https:\/\/wp-modula.b-cdn.net\/spai\/q_lossless,ret_img\/https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/10\/f-_MG_1202-copy.jpg\" title=\"Rze\u017abienie w drewnie\" data-caption=\"Osoba w r\u0119kawicach d\u0142utuje drewniany element, z kt\u00f3rego powstaj\u0105 wi\u00f3ry.\" src=\"https:\/\/wp-modula.b-cdn.net\/spai\/q_lossless,ret_img,w_1024,h_683\/https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/10\/f-_MG_1202-copy-scaled-1024x683.jpg\" data-src=\"https:\/\/wp-modula.b-cdn.net\/spai\/q_lossless,ret_img,w_1024,h_683\/https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/10\/f-_MG_1202-copy-scaled-1024x683.jpg\" width=\"1024\" height=\"683\"\/>\n\t\t<div class=\"figc\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo jtg-filter-all jtg-filter-\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t\t\t\n\t\t\t\t\t<a role=\"button\" tabindex=\"0\" rel=\"jtg-61434\" data-caption=\"\" aria-label=\"Open image in lightbox\" data-thumb=\"https:\/\/wp-modula.b-cdn.net\/spai\/q_lossless,ret_img,w_150,h_150\/https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/10\/f-_MG_1209-copy-150x150.jpg\" class=\"tile-inner modula-item-link\"><\/a>\n\t\t\n\t\t<img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-69829\"  data-valign=\"middle\" data-halign=\"center\" alt=\"R\u0119ce w r\u0119kawicach rze\u017abi\u0105 zakrzywiony drewniany element na stole z wi\u00f3rami.\" data-full=\"https:\/\/wp-modula.b-cdn.net\/spai\/q_lossless,ret_img\/https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/10\/f-_MG_1209-copy.jpg\" title=\"Precyzyjna praca stolarska przy drewnianym elemencie\" data-caption=\"Osoba w r\u0119kawicach wykonuje precyzyjn\u0105 prac\u0119 stolarsk\u0105, rze\u017abi\u0105c lub wyg\u0142adzaj\u0105c drewniany element o zakrzywionym kszta\u0142cie, na stole znajduj\u0105 si\u0119 drobne wi\u00f3ry drewniane.\" src=\"https:\/\/wp-modula.b-cdn.net\/spai\/q_lossless,ret_img,w_1024,h_683\/https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/10\/f-_MG_1209-copy-scaled-1024x683.jpg\" data-src=\"https:\/\/wp-modula.b-cdn.net\/spai\/q_lossless,ret_img,w_1024,h_683\/https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/10\/f-_MG_1209-copy-scaled-1024x683.jpg\" width=\"1024\" height=\"683\"\/>\n\t\t<div class=\"figc\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo jtg-filter-all jtg-filter-\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t\t\t\n\t\t\t\t\t<a role=\"button\" tabindex=\"0\" rel=\"jtg-61434\" data-caption=\"\" aria-label=\"Open image in lightbox\" data-thumb=\"https:\/\/wp-modula.b-cdn.net\/spai\/q_lossless,ret_img,w_150,h_150\/https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/10\/f-_MG_1214-copy-150x150.jpg\" class=\"tile-inner modula-item-link\"><\/a>\n\t\t\n\t\t<img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-69835\"  data-valign=\"middle\" data-halign=\"center\" alt=\"Rzemie\u015blnik wyg\u0142adza drewniany element o \u0142ukowatym kszta\u0142cie na stole warsztatowym.\" data-full=\"https:\/\/wp-modula.b-cdn.net\/spai\/q_lossless,ret_img\/https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/10\/f-_MG_1214-copy.jpg\" title=\"Rzemie\u015blnik wyg\u0142adzaj\u0105cy drewniany element przy stole warsztatowym\" data-caption=\"Rzemie\u015blnik pracuje nad drewnianym elementem przy du\u017cym stole warsztatowym, u\u017cywaj\u0105c narz\u0119dzia do wyka\u0144czania i wyg\u0142adzania drewna. Na stole le\u017c\u0105 wi\u00f3ry drewniane oraz dwa wycinane kawa\u0142ki drewna o \u0142ukowatym kszta\u0142cie. M\u0119\u017cczyzna ma na r\u0119kach bia\u0142e r\u0119kawice ochronne.\" src=\"https:\/\/wp-modula.b-cdn.net\/spai\/q_lossless,ret_img,w_1024,h_683\/https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/10\/f-_MG_1214-copy-scaled-1024x683.jpg\" data-src=\"https:\/\/wp-modula.b-cdn.net\/spai\/q_lossless,ret_img,w_1024,h_683\/https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/10\/f-_MG_1214-copy-scaled-1024x683.jpg\" width=\"1024\" height=\"683\"\/>\n\t\t<div class=\"figc\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo jtg-filter-all jtg-filter-\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t\t\t\n\t\t\t\t\t<a role=\"button\" tabindex=\"0\" rel=\"jtg-61434\" data-caption=\"\" aria-label=\"Open image in lightbox\" data-thumb=\"https:\/\/wp-modula.b-cdn.net\/spai\/q_lossless,ret_img,w_150,h_150\/https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/10\/f-_MG_1238-copy-150x150.jpg\" class=\"tile-inner modula-item-link\"><\/a>\n\t\t\n\t\t<img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-69847\"  data-valign=\"middle\" data-halign=\"center\" alt=\"R\u0119ce w r\u0119kawiczkach rze\u017abi\u0105 drewniany element przy u\u017cyciu d\u0142uta, otoczone wi\u00f3rami.\" data-full=\"https:\/\/wp-modula.b-cdn.net\/spai\/q_lossless,ret_img\/https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/10\/f-_MG_1238-copy.jpg\" title=\"Precyzyjne rze\u017abienie w drewnie d\u0142utem\" data-caption=\"R\u0119ce w r\u0119kawiczkach wykonuj\u0105 precyzyjne rze\u017abienie w drewnianym elemencie przy u\u017cyciu d\u0142uta, otoczone wi\u00f3rami drewnianymi.\" src=\"https:\/\/wp-modula.b-cdn.net\/spai\/q_lossless,ret_img,w_1024,h_683\/https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/10\/f-_MG_1238-copy-scaled-1024x683.jpg\" data-src=\"https:\/\/wp-modula.b-cdn.net\/spai\/q_lossless,ret_img,w_1024,h_683\/https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/10\/f-_MG_1238-copy-scaled-1024x683.jpg\" width=\"1024\" height=\"683\"\/>\n\t\t<div class=\"figc\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo jtg-filter-all jtg-filter-\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t\t\t\n\t\t\t\t\t<a role=\"button\" tabindex=\"0\" rel=\"jtg-61434\" data-caption=\"\" aria-label=\"Open image in lightbox\" data-thumb=\"https:\/\/wp-modula.b-cdn.net\/spai\/q_lossless,ret_img,w_150,h_150\/https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/10\/f-_MG_1266-copy-150x150.jpg\" class=\"tile-inner modula-item-link\"><\/a>\n\t\t\n\t\t<img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-69859\"  data-valign=\"middle\" data-halign=\"center\" alt=\"R\u0119ka w bia\u0142ej r\u0119kawicy rze\u017abi drewno d\u0142utem na drewnianym stole z ko\u0142kami.\" data-full=\"https:\/\/wp-modula.b-cdn.net\/spai\/q_lossless,ret_img\/https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/10\/f-_MG_1266-copy.jpg\" title=\"Szlifowanie drewna d\u0142utem z bia\u0142\u0105 r\u0119kawic\u0105\" data-caption=\"R\u0119ka w bia\u0142ej r\u0119kawicy szlifuje kawa\u0142ek drewna za pomoc\u0105 d\u0142uta, na tle powierzchni drewnianej konstrukcji z elementami mocowanymi za pomoc\u0105 drewnianych ko\u0142k\u00f3w.\" src=\"https:\/\/wp-modula.b-cdn.net\/spai\/q_lossless,ret_img,w_1024,h_683\/https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/10\/f-_MG_1266-copy-scaled-1024x683.jpg\" data-src=\"https:\/\/wp-modula.b-cdn.net\/spai\/q_lossless,ret_img,w_1024,h_683\/https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/10\/f-_MG_1266-copy-scaled-1024x683.jpg\" width=\"1024\" height=\"683\"\/>\n\t\t<div class=\"figc\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo jtg-filter-all jtg-filter-\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t\t\t\n\t\t\t\t\t<a role=\"button\" tabindex=\"0\" rel=\"jtg-61434\" data-caption=\"\" aria-label=\"Open image in lightbox\" data-thumb=\"https:\/\/wp-modula.b-cdn.net\/spai\/q_lossless,ret_img,w_150,h_150\/https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/10\/f-_MG_1257-copy-150x150.jpg\" class=\"tile-inner modula-item-link\"><\/a>\n\t\t\n\t\t<img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-69853\"  data-valign=\"middle\" data-halign=\"center\" alt=\"R\u0119ka w bia\u0142ej r\u0119kawicy d\u0142utuje drewniany element, powstaje spirala wi\u00f3ra.\" data-full=\"https:\/\/wp-modula.b-cdn.net\/spai\/q_lossless,ret_img\/https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/10\/f-_MG_1257-copy.jpg\" title=\"Obr\u00f3bka drewna d\u0142utem w bia\u0142ej r\u0119kawicy\" data-caption=\"R\u0119ka w bia\u0142ej r\u0119kawicy obrabia drewniany element za pomoc\u0105 d\u0142uta, z drewna powstaje wi\u00f3r w kszta\u0142cie spirali.\" src=\"https:\/\/wp-modula.b-cdn.net\/spai\/q_lossless,ret_img,w_1024,h_683\/https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/10\/f-_MG_1257-copy-scaled-1024x683.jpg\" data-src=\"https:\/\/wp-modula.b-cdn.net\/spai\/q_lossless,ret_img,w_1024,h_683\/https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/10\/f-_MG_1257-copy-scaled-1024x683.jpg\" width=\"1024\" height=\"683\"\/>\n\t\t<div class=\"figc\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo jtg-filter-all jtg-filter-\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t\t\t\n\t\t\t\t\t<a role=\"button\" tabindex=\"0\" rel=\"jtg-61434\" data-caption=\"\" aria-label=\"Open image in lightbox\" data-thumb=\"https:\/\/wp-modula.b-cdn.net\/spai\/q_lossless,ret_img,w_150,h_150\/https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/10\/f-_MG_1283-copy-150x150.jpg\" class=\"tile-inner modula-item-link\"><\/a>\n\t\t\n\t\t<img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-69865\"  data-valign=\"middle\" data-halign=\"center\" alt=\"M\u0119\u017cczyzna z r\u0119kawicami rze\u017abi drewniany element przy stole warsztatowym d\u0142utem.\" data-full=\"https:\/\/wp-modula.b-cdn.net\/spai\/q_lossless,ret_img\/https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/10\/f-_MG_1283-copy.jpg\" title=\"M\u0119\u017cczyzna rze\u017abi\u0105cy drewno d\u0142utem na stole warsztatowym\" data-caption=\"M\u0119\u017cczyzna w r\u0119kawicach pracuje nad drewnianym elementem na stole warsztatowym, u\u017cywaj\u0105c d\u0142uta do precyzyjnego rze\u017abienia drewna. Obok le\u017cy kolejne d\u0142uto z \u017c\u00f3\u0142t\u0105 r\u0105czk\u0105, a na stole wida\u0107 wi\u00f3ry drewniane.\" src=\"https:\/\/wp-modula.b-cdn.net\/spai\/q_lossless,ret_img,w_1024,h_683\/https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/10\/f-_MG_1283-copy-scaled-1024x683.jpg\" data-src=\"https:\/\/wp-modula.b-cdn.net\/spai\/q_lossless,ret_img,w_1024,h_683\/https:\/\/saprenovation.com\/wp-content\/uploads\/2025\/10\/f-_MG_1283-copy-scaled-1024x683.jpg\" width=\"1024\" height=\"683\"\/>\n\t\t<div class=\"figc\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div>\t\t\n\t<\/div>\n\n\t\n\t\n\t<script type=\"application\/ld+json\">\n\t{\n\t\t\"@context\": \"http:\/\/schema.org\",\n\t\t\"@type\"   : \"ImageGallery\",\n\t\t\"id\"      : \"https:\/\/saprenovation.com\/fr\/alaudis-stara\/\",\n\t\t\"url\"     : \"https:\/\/saprenovation.com\/fr\/alaudis-stara\/\"\n\t}\n\n\t<\/script>\n\n\t\n<\/div>\n\n<\/div>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Alaudis SAP Alaudis est un piano extraordinaire con\u00e7u pour capturer la beaut\u00e9 et le son enchanteurs du chant de l&rsquo;alouette. M\u00e9ticuleusement fabriqu\u00e9 par une \u00e9quipe d&rsquo;artisans et d&rsquo;ing\u00e9nieurs qualifi\u00e9s,&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-full-width","meta":{"footnotes":""},"class_list":["post-58864","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Alaudis - SAP Renovation<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/saprenovation.com\/fr\/alaudis-stara\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Alaudis - SAP Renovation\" \/>\n<meta property=\"og:description\" content=\"Alaudis SAP Alaudis est un piano extraordinaire con\u00e7u pour capturer la beaut\u00e9 et le son enchanteurs du chant de l&rsquo;alouette. M\u00e9ticuleusement fabriqu\u00e9 par une \u00e9quipe d&rsquo;artisans et d&rsquo;ing\u00e9nieurs qualifi\u00e9s,...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/saprenovation.com\/fr\/alaudis-stara\/\" \/>\n<meta property=\"og:site_name\" content=\"SAP Renovation\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/saprenovation\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-28T17:47:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/saprenovation.com\/wp-content\/uploads\/2024\/10\/xlogo.png.pagespeed.ic_.pCcv2wiNk5.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"112\" \/>\n\t<meta property=\"og:image:height\" content=\"96\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/saprenovation.com\/fr\/alaudis-stara\/\",\"url\":\"https:\/\/saprenovation.com\/fr\/alaudis-stara\/\",\"name\":\"Alaudis - SAP Renovation\",\"isPartOf\":{\"@id\":\"https:\/\/saprenovation.com\/fr\/#website\"},\"datePublished\":\"2024-05-06T11:02:37+00:00\",\"dateModified\":\"2025-10-28T17:47:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/saprenovation.com\/fr\/alaudis-stara\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/saprenovation.com\/fr\/alaudis-stara\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/saprenovation.com\/fr\/alaudis-stara\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"SAP Renovation\",\"item\":\"https:\/\/saprenovation.com\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Alaudis\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/saprenovation.com\/fr\/#website\",\"url\":\"https:\/\/saprenovation.com\/fr\/\",\"name\":\"SAP Renovation\",\"description\":\"The finest European piano restoration\",\"publisher\":{\"@id\":\"https:\/\/saprenovation.com\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/saprenovation.com\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/saprenovation.com\/fr\/#organization\",\"name\":\"SAP Renovation\",\"alternateName\":\"Profesjonalna Renowacja Fortepian\u00f3w\",\"url\":\"https:\/\/saprenovation.com\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/saprenovation.com\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/saprenovation.com\/wp-content\/uploads\/2024\/04\/xlogo.png.pagespeed.ic_.pCcv2wiNk5.webp\",\"contentUrl\":\"https:\/\/saprenovation.com\/wp-content\/uploads\/2024\/04\/xlogo.png.pagespeed.ic_.pCcv2wiNk5.webp\",\"width\":112,\"height\":96,\"caption\":\"SAP Renovation\"},\"image\":{\"@id\":\"https:\/\/saprenovation.com\/fr\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/saprenovation\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Alaudis - SAP Renovation","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/saprenovation.com\/fr\/alaudis-stara\/","og_locale":"fr_FR","og_type":"article","og_title":"Alaudis - SAP Renovation","og_description":"Alaudis SAP Alaudis est un piano extraordinaire con\u00e7u pour capturer la beaut\u00e9 et le son enchanteurs du chant de l&rsquo;alouette. M\u00e9ticuleusement fabriqu\u00e9 par une \u00e9quipe d&rsquo;artisans et d&rsquo;ing\u00e9nieurs qualifi\u00e9s,...","og_url":"https:\/\/saprenovation.com\/fr\/alaudis-stara\/","og_site_name":"SAP Renovation","article_publisher":"https:\/\/www.facebook.com\/saprenovation\/","article_modified_time":"2025-10-28T17:47:38+00:00","og_image":[{"width":112,"height":96,"url":"https:\/\/saprenovation.com\/wp-content\/uploads\/2024\/10\/xlogo.png.pagespeed.ic_.pCcv2wiNk5.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/saprenovation.com\/fr\/alaudis-stara\/","url":"https:\/\/saprenovation.com\/fr\/alaudis-stara\/","name":"Alaudis - SAP Renovation","isPartOf":{"@id":"https:\/\/saprenovation.com\/fr\/#website"},"datePublished":"2024-05-06T11:02:37+00:00","dateModified":"2025-10-28T17:47:38+00:00","breadcrumb":{"@id":"https:\/\/saprenovation.com\/fr\/alaudis-stara\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/saprenovation.com\/fr\/alaudis-stara\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/saprenovation.com\/fr\/alaudis-stara\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"SAP Renovation","item":"https:\/\/saprenovation.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Alaudis"}]},{"@type":"WebSite","@id":"https:\/\/saprenovation.com\/fr\/#website","url":"https:\/\/saprenovation.com\/fr\/","name":"SAP Renovation","description":"The finest European piano restoration","publisher":{"@id":"https:\/\/saprenovation.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/saprenovation.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/saprenovation.com\/fr\/#organization","name":"SAP Renovation","alternateName":"Profesjonalna Renowacja Fortepian\u00f3w","url":"https:\/\/saprenovation.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/saprenovation.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/saprenovation.com\/wp-content\/uploads\/2024\/04\/xlogo.png.pagespeed.ic_.pCcv2wiNk5.webp","contentUrl":"https:\/\/saprenovation.com\/wp-content\/uploads\/2024\/04\/xlogo.png.pagespeed.ic_.pCcv2wiNk5.webp","width":112,"height":96,"caption":"SAP Renovation"},"image":{"@id":"https:\/\/saprenovation.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/saprenovation\/"]}]}},"_links":{"self":[{"href":"https:\/\/saprenovation.com\/fr\/wp-json\/wp\/v2\/pages\/58864","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/saprenovation.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/saprenovation.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/saprenovation.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/saprenovation.com\/fr\/wp-json\/wp\/v2\/comments?post=58864"}],"version-history":[{"count":3,"href":"https:\/\/saprenovation.com\/fr\/wp-json\/wp\/v2\/pages\/58864\/revisions"}],"predecessor-version":[{"id":61437,"href":"https:\/\/saprenovation.com\/fr\/wp-json\/wp\/v2\/pages\/58864\/revisions\/61437"}],"wp:attachment":[{"href":"https:\/\/saprenovation.com\/fr\/wp-json\/wp\/v2\/media?parent=58864"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}